{"id":1125,"date":"2023-08-08T19:41:56","date_gmt":"2023-08-08T17:41:56","guid":{"rendered":"http:\/\/82.65.63.100\/wordpress\/?p=1125"},"modified":"2023-08-26T08:11:13","modified_gmt":"2023-08-26T06:11:13","slug":"euro-2025","status":"publish","type":"post","link":"http:\/\/82.65.63.100\/wordpress\/blog\/2023\/08\/08\/euro-2025\/","title":{"rendered":"Qualification Eurobasket 2025"},"content":{"rendered":"\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:45%\">\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"FIBA EuroBasket 2025 Qualifiers | Draw\" width=\"680\" height=\"383\" src=\"https:\/\/www.youtube.com\/embed\/OtfuSJlh0jo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>En marge de la coupe du monde , et un an avant les jeux olympiques, la FIBA a proc\u00e9d\u00e9 au tirage au sort des groupes \u00e9liminatoires pour l&rsquo;Eurobasket 2025 qui se d\u00e9roulera en Lettonie, Chypre, Finlande et Pologne. les premiers matches de qualification pour l\u2019Euro 2025 auront lieu du 19 au 27 f\u00e9vrier 2024. Les deux autres fen\u00eatres internationales auront lieu du 18 au 26 novembre 2024 et du 17 au 25 f\u00e9vrier 2025.<\/p>\n<\/div>\n<\/div>\n\n\n\n<p>T\u00eate de s\u00e9rie, la France n&rsquo;a pas vraiment profit\u00e9 de son statut de favori puisqu&rsquo;elle est tomb\u00e9e dans le groupe E avec la Croatie, la Bosnie-Herz\u00e9govine et Chypre. En tant que pays organisateur Chypre est automatiquement qualifi\u00e9 pour la phase finale. Il faudra donc finir \u00e0 l&rsquo;une des deux premi\u00e8res places. 24 \u00e9quipes joueront leur qualification parmi les 8 groupes tir\u00e9s au sort:<\/p>\n\n\n\n<p>Groupe A: Slov\u00e9nie, Ukraine, Isra\u00ebl, Portugal<br>Groupe B: Italie, Turquie, Hongrie, Islande<br>Groupe C: Espagne, Lettonie, Belgique, Slovaquie<br>Groupe D: Allemagne Mont\u00e9n\u00e9gro, Bulgarie, Su\u00e8de<br>Groupe E: France, Croatie, Bosnie-Herz\u00e9govine, Chypre<br>Groupe F: Gr\u00e8ce, R\u00e9publique Tch\u00e8que, Pays-Bas, Grande Bretagne<br>Groupe G: Serbie, Finlande, G\u00e9orgie, Danemark,<br>Groupe H: Lituanie, Pologne, Estonie, Mac\u00e9doine du Nord<\/p>\n\n\n\n<p class=\"has-text-align-right has-vivid-red-color has-text-color\" style=\"font-style:normal;font-weight:700\"><a href=\"https:\/\/www.fiba.basketball\/eurobasket\/2025\/qualifiers\/\" target=\"_blank\" rel=\"noreferrer noopener\">Site officiel de l&rsquo;Eurobasket 2025<\/a> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>En marge de la coupe du monde , et un an avant les jeux olympiques, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1138,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"editor_plus_copied_stylings":"{}","footnotes":""},"categories":[14],"tags":[52,24,50,51,17],"class_list":["post-1125","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actu-basket","tag-52","tag-basketball","tag-eurobasket","tag-qualification","tag-fiba"],"_links":{"self":[{"href":"http:\/\/82.65.63.100\/wordpress\/wp-json\/wp\/v2\/posts\/1125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/82.65.63.100\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/82.65.63.100\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/82.65.63.100\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/82.65.63.100\/wordpress\/wp-json\/wp\/v2\/comments?post=1125"}],"version-history":[{"count":13,"href":"http:\/\/82.65.63.100\/wordpress\/wp-json\/wp\/v2\/posts\/1125\/revisions"}],"predecessor-version":[{"id":2112,"href":"http:\/\/82.65.63.100\/wordpress\/wp-json\/wp\/v2\/posts\/1125\/revisions\/2112"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/82.65.63.100\/wordpress\/wp-json\/wp\/v2\/media\/1138"}],"wp:attachment":[{"href":"http:\/\/82.65.63.100\/wordpress\/wp-json\/wp\/v2\/media?parent=1125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/82.65.63.100\/wordpress\/wp-json\/wp\/v2\/categories?post=1125"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/82.65.63.100\/wordpress\/wp-json\/wp\/v2\/tags?post=1125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}